{"id":5578,"date":"2026-01-05T08:51:41","date_gmt":"2026-01-05T08:51:41","guid":{"rendered":"https:\/\/saletosama.com\/?post_type=product&#038;p=5578"},"modified":"2026-01-11T20:28:08","modified_gmt":"2026-01-11T20:28:08","slug":"%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1","status":"publish","type":"product","link":"https:\/\/www.saletosama.com\/en\/product\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\/","title":{"rendered":"\u062c\u0631\u062c\u064a\u0631"},"content":{"rendered":"<p data-path-to-node=\"7\"><span class=\"\">\u0627\u0644\u062c\u0631\u062c\u064a\u0631 \u0627\u0644\u0628\u0644\u062f\u064a \u0627\u0644\u0637\u0627\u0632\u062c\u060c \u0645\u0644\u0643 \u0627\u0644\u062e\u0636\u0631\u0648\u0627\u062a \u0627\u0644\u0648\u0631\u0642\u064a\u0629 \u0628\u0641\u0648\u0627\u0626\u062f\u0647 \u0627\u0644\u0644\u064a \u0645\u0627\u0628\u062a\u062e\u0644\u0635\u0634 \u0648\u0637\u0639\u0645\u0647 \u0627\u0644\u0645\u0645\u064a\u0632.<\/span><span class=\"\"> \u0645\u0646\u062a\u0642\u0649 \u0628\u0639\u0646\u0627\u064a\u0629 \u0639\u0634\u0627\u0646 \u064a\u0648\u0635\u0644\u0643 \u0641\u0631\u064a\u0634 \u0648\u0646\u0638\u064a\u0641 \u062a\u0645\u0627\u0645\u0627\u064b.<\/span><\/p>\n<p data-path-to-node=\"8\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-5582\" src=\"https:\/\/saletosama.com\/wp-content\/uploads\/2026\/01\/unnamed-1-1-272x272.jpg\" alt=\"\" width=\"272\" height=\"272\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-5584\" src=\"https:\/\/saletosama.com\/wp-content\/uploads\/2026\/01\/unnamed-3-272x272.jpg\" alt=\"\" width=\"272\" height=\"272\" \/><\/p>","protected":false},"excerpt":{"rendered":"<blockquote data-path-to-node=\"24\">\n<p data-path-to-node=\"24,0\"><b data-path-to-node=\"24,0\" data-index-in-node=\"0\">\u0631\u0628\u0637\u0629 \u062c\u0631\u062c\u064a\u0631 \u0628\u0644\u062f\u064a \u0637\u0627\u0632\u062c\u0629\u060c \u0645\u063a\u0633\u0648\u0644\u0629 \u0648\u0645\u0639\u0628\u0623\u0629 \u0628\u0639\u0646\u0627\u064a\u0629. \u0637\u0639\u0645 \u0642\u0648\u064a \u0648\u0641\u0648\u0627\u0626\u062f \u0635\u062d\u064a\u0629 \u0644\u0627 \u062d\u0635\u0631 \u0644\u0647\u0627\u060c \u0645\u062b\u0627\u0644\u064a\u0629 \u0644\u0644\u0633\u0644\u0637\u0627\u062a \u0648\u0627\u0644\u0648\u062c\u0628\u0627\u062a \u0627\u0644\u064a\u0648\u0645\u064a\u0629.<\/b><\/p>\n<\/blockquote>","protected":false},"featured_media":5580,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[89],"product_tag":[],"class_list":{"0":"post-5578","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-89","8":"first","9":"instock","10":"featured","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"ams_default_variation_id":0,"ams_product_points_reward":[],"ams_product_discount_percentage":0,"ams_price_to_display":3,"ams_acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u062c\u0631\u062c\u064a\u0631 \u0637\u0627\u0632\u062c \u0648\u0645\u063a\u0633\u0648\u0644 | Fresh Arugula | \u0633\u0644\u0629 \u0623\u0633\u0627\u0645\u0629<\/title>\n<meta name=\"description\" content=\"\u0627\u0637\u0644\u0628 \u062c\u0631\u062c\u064a\u0631 \u0637\u0627\u0632\u062c \u0648\u0645\u063a\u0633\u0648\u0644 \u0628\u062c\u0648\u062f\u0629 \u0628\u0631\u064a\u0645\u064a\u0648\u0645 \u0645\u0646 \u0633\u0644\u0629 \u0623\u0633\u0627\u0645\u0629. \u063a\u0646\u064a \u0628\u0627\u0644\u0641\u064a\u062a\u0627\u0645\u064a\u0646\u0627\u062a \u0648\u0645\u062b\u0627\u0644\u064a \u0644\u0646\u0638\u0627\u0645\u0643 \u0627\u0644\u063a\u0630\u0627\u0626\u064a \u0627\u0644\u0635\u062d\u064a. Fresh Arugula for a healthy lifestyle. \u0627\u0637\u0644\u0628\u0647 \u0627\u0644\u0622\u0646!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.saletosama.com\/en\/product\/\u062c\u0631\u062c\u064a\u0631\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062c\u0631\u062c\u064a\u0631 \u0637\u0627\u0632\u062c \u0648\u0645\u063a\u0633\u0648\u0644 | Fresh Arugula | \u0633\u0644\u0629 \u0623\u0633\u0627\u0645\u0629\" \/>\n<meta property=\"og:description\" content=\"\u0627\u0637\u0644\u0628 \u062c\u0631\u062c\u064a\u0631 \u0637\u0627\u0632\u062c \u0648\u0645\u063a\u0633\u0648\u0644 \u0628\u062c\u0648\u062f\u0629 \u0628\u0631\u064a\u0645\u064a\u0648\u0645 \u0645\u0646 \u0633\u0644\u0629 \u0623\u0633\u0627\u0645\u0629. \u063a\u0646\u064a \u0628\u0627\u0644\u0641\u064a\u062a\u0627\u0645\u064a\u0646\u0627\u062a \u0648\u0645\u062b\u0627\u0644\u064a \u0644\u0646\u0638\u0627\u0645\u0643 \u0627\u0644\u063a\u0630\u0627\u0626\u064a \u0627\u0644\u0635\u062d\u064a. Fresh Arugula for a healthy lifestyle. \u0627\u0637\u0644\u0628\u0647 \u0627\u0644\u0622\u0646!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.saletosama.com\/en\/product\/\u062c\u0631\u062c\u064a\u0631\/\" \/>\n<meta property=\"og:site_name\" content=\"saletosama\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-11T20:28:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.saletosama.com\/wp-content\/uploads\/2026\/01\/unnamed-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.saletosama.com\\\/product\\\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\\\/\",\"url\":\"https:\\\/\\\/www.saletosama.com\\\/product\\\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\\\/\",\"name\":\"\u062c\u0631\u062c\u064a\u0631 \u0637\u0627\u0632\u062c \u0648\u0645\u063a\u0633\u0648\u0644 | Fresh Arugula | \u0633\u0644\u0629 \u0623\u0633\u0627\u0645\u0629\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.saletosama.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.saletosama.com\\\/product\\\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saletosama.com\\\/product\\\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.saletosama.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/unnamed-1.jpg\",\"datePublished\":\"2026-01-05T08:51:41+00:00\",\"dateModified\":\"2026-01-11T20:28:08+00:00\",\"description\":\"\u0627\u0637\u0644\u0628 \u062c\u0631\u062c\u064a\u0631 \u0637\u0627\u0632\u062c \u0648\u0645\u063a\u0633\u0648\u0644 \u0628\u062c\u0648\u062f\u0629 \u0628\u0631\u064a\u0645\u064a\u0648\u0645 \u0645\u0646 \u0633\u0644\u0629 \u0623\u0633\u0627\u0645\u0629. \u063a\u0646\u064a \u0628\u0627\u0644\u0641\u064a\u062a\u0627\u0645\u064a\u0646\u0627\u062a \u0648\u0645\u062b\u0627\u0644\u064a \u0644\u0646\u0638\u0627\u0645\u0643 \u0627\u0644\u063a\u0630\u0627\u0626\u064a \u0627\u0644\u0635\u062d\u064a. Fresh Arugula for a healthy lifestyle. \u0627\u0637\u0644\u0628\u0647 \u0627\u0644\u0622\u0646!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.saletosama.com\\\/product\\\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.saletosama.com\\\/product\\\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.saletosama.com\\\/product\\\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.saletosama.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/unnamed-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.saletosama.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/unnamed-1.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.saletosama.com\\\/product\\\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.saletosama.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0643\u0644 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a\",\"item\":\"https:\\\/\\\/www.saletosama.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u062c\u0631\u062c\u064a\u0631\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.saletosama.com\\\/#website\",\"url\":\"https:\\\/\\\/www.saletosama.com\\\/\",\"name\":\"saletosama\",\"description\":\"Grocery store\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.saletosama.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.saletosama.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.saletosama.com\\\/#organization\",\"name\":\"saletosama\",\"url\":\"https:\\\/\\\/www.saletosama.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.saletosama.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.saletosama.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ss.pdf-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/www.saletosama.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ss.pdf-scaled.webp\",\"width\":2560,\"height\":2560,\"caption\":\"saletosama\"},\"image\":{\"@id\":\"https:\\\/\\\/www.saletosama.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u062c\u0631\u062c\u064a\u0631 \u0637\u0627\u0632\u062c \u0648\u0645\u063a\u0633\u0648\u0644 | Fresh Arugula | \u0633\u0644\u0629 \u0623\u0633\u0627\u0645\u0629","description":"\u0627\u0637\u0644\u0628 \u062c\u0631\u062c\u064a\u0631 \u0637\u0627\u0632\u062c \u0648\u0645\u063a\u0633\u0648\u0644 \u0628\u062c\u0648\u062f\u0629 \u0628\u0631\u064a\u0645\u064a\u0648\u0645 \u0645\u0646 \u0633\u0644\u0629 \u0623\u0633\u0627\u0645\u0629. \u063a\u0646\u064a \u0628\u0627\u0644\u0641\u064a\u062a\u0627\u0645\u064a\u0646\u0627\u062a \u0648\u0645\u062b\u0627\u0644\u064a \u0644\u0646\u0638\u0627\u0645\u0643 \u0627\u0644\u063a\u0630\u0627\u0626\u064a \u0627\u0644\u0635\u062d\u064a. Fresh Arugula for a healthy lifestyle. \u0627\u0637\u0644\u0628\u0647 \u0627\u0644\u0622\u0646!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.saletosama.com\/en\/product\/\u062c\u0631\u062c\u064a\u0631\/","og_locale":"en_US","og_type":"article","og_title":"\u062c\u0631\u062c\u064a\u0631 \u0637\u0627\u0632\u062c \u0648\u0645\u063a\u0633\u0648\u0644 | Fresh Arugula | \u0633\u0644\u0629 \u0623\u0633\u0627\u0645\u0629","og_description":"\u0627\u0637\u0644\u0628 \u062c\u0631\u062c\u064a\u0631 \u0637\u0627\u0632\u062c \u0648\u0645\u063a\u0633\u0648\u0644 \u0628\u062c\u0648\u062f\u0629 \u0628\u0631\u064a\u0645\u064a\u0648\u0645 \u0645\u0646 \u0633\u0644\u0629 \u0623\u0633\u0627\u0645\u0629. \u063a\u0646\u064a \u0628\u0627\u0644\u0641\u064a\u062a\u0627\u0645\u064a\u0646\u0627\u062a \u0648\u0645\u062b\u0627\u0644\u064a \u0644\u0646\u0638\u0627\u0645\u0643 \u0627\u0644\u063a\u0630\u0627\u0626\u064a \u0627\u0644\u0635\u062d\u064a. Fresh Arugula for a healthy lifestyle. \u0627\u0637\u0644\u0628\u0647 \u0627\u0644\u0622\u0646!","og_url":"https:\/\/www.saletosama.com\/en\/product\/\u062c\u0631\u062c\u064a\u0631\/","og_site_name":"saletosama","article_modified_time":"2026-01-11T20:28:08+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.saletosama.com\/wp-content\/uploads\/2026\/01\/unnamed-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.saletosama.com\/product\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\/","url":"https:\/\/www.saletosama.com\/product\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\/","name":"\u062c\u0631\u062c\u064a\u0631 \u0637\u0627\u0632\u062c \u0648\u0645\u063a\u0633\u0648\u0644 | Fresh Arugula | \u0633\u0644\u0629 \u0623\u0633\u0627\u0645\u0629","isPartOf":{"@id":"https:\/\/www.saletosama.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.saletosama.com\/product\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\/#primaryimage"},"image":{"@id":"https:\/\/www.saletosama.com\/product\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.saletosama.com\/wp-content\/uploads\/2026\/01\/unnamed-1.jpg","datePublished":"2026-01-05T08:51:41+00:00","dateModified":"2026-01-11T20:28:08+00:00","description":"\u0627\u0637\u0644\u0628 \u062c\u0631\u062c\u064a\u0631 \u0637\u0627\u0632\u062c \u0648\u0645\u063a\u0633\u0648\u0644 \u0628\u062c\u0648\u062f\u0629 \u0628\u0631\u064a\u0645\u064a\u0648\u0645 \u0645\u0646 \u0633\u0644\u0629 \u0623\u0633\u0627\u0645\u0629. \u063a\u0646\u064a \u0628\u0627\u0644\u0641\u064a\u062a\u0627\u0645\u064a\u0646\u0627\u062a \u0648\u0645\u062b\u0627\u0644\u064a \u0644\u0646\u0638\u0627\u0645\u0643 \u0627\u0644\u063a\u0630\u0627\u0626\u064a \u0627\u0644\u0635\u062d\u064a. Fresh Arugula for a healthy lifestyle. \u0627\u0637\u0644\u0628\u0647 \u0627\u0644\u0622\u0646!","breadcrumb":{"@id":"https:\/\/www.saletosama.com\/product\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.saletosama.com\/product\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.saletosama.com\/product\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\/#primaryimage","url":"https:\/\/www.saletosama.com\/wp-content\/uploads\/2026\/01\/unnamed-1.jpg","contentUrl":"https:\/\/www.saletosama.com\/wp-content\/uploads\/2026\/01\/unnamed-1.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/www.saletosama.com\/product\/%d8%ac%d8%b1%d8%ac%d9%8a%d8%b1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.saletosama.com\/"},{"@type":"ListItem","position":2,"name":"\u0643\u0644 \u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a","item":"https:\/\/www.saletosama.com\/shop\/"},{"@type":"ListItem","position":3,"name":"\u062c\u0631\u062c\u064a\u0631"}]},{"@type":"WebSite","@id":"https:\/\/www.saletosama.com\/#website","url":"https:\/\/www.saletosama.com\/","name":"saletosama","description":"Grocery store","publisher":{"@id":"https:\/\/www.saletosama.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.saletosama.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.saletosama.com\/#organization","name":"saletosama","url":"https:\/\/www.saletosama.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.saletosama.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.saletosama.com\/wp-content\/uploads\/2025\/12\/ss.pdf-scaled.webp","contentUrl":"https:\/\/www.saletosama.com\/wp-content\/uploads\/2025\/12\/ss.pdf-scaled.webp","width":2560,"height":2560,"caption":"saletosama"},"image":{"@id":"https:\/\/www.saletosama.com\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.saletosama.com\/en\/wp-json\/wp\/v2\/product\/5578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.saletosama.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.saletosama.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.saletosama.com\/en\/wp-json\/wp\/v2\/comments?post=5578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.saletosama.com\/en\/wp-json\/wp\/v2\/media\/5580"}],"wp:attachment":[{"href":"https:\/\/www.saletosama.com\/en\/wp-json\/wp\/v2\/media?parent=5578"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.saletosama.com\/en\/wp-json\/wp\/v2\/product_brand?post=5578"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.saletosama.com\/en\/wp-json\/wp\/v2\/product_cat?post=5578"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.saletosama.com\/en\/wp-json\/wp\/v2\/product_tag?post=5578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}